{"id":400,"count":1,"description":"","link":"https:\/\/berlintrend.eu\/uk\/tag\/%d0%be%d0%bf%d0%b5%d1%80%d0%b5%d1%82%d0%b0","name":"\u043e\u043f\u0435\u0440\u0435\u0442\u0430","slug":"%d0%be%d0%bf%d0%b5%d1%80%d0%b5%d1%82%d0%b0","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/berlintrend.eu\/uk\/wp-json\/wp\/v2\/tags\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/berlintrend.eu\/uk\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/berlintrend.eu\/uk\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/berlintrend.eu\/uk\/wp-json\/wp\/v2\/posts?tags=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}